{"id":856,"date":"2024-01-16T11:46:45","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=856"},"modified":"2025-04-02T15:24:00","modified_gmt":"2025-04-02T12:24:00","slug":"blister-packing-machine-for-portioned-products-nm-25","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-equipamento\/equipamento-de-embalamento-automatico\/equipamento-automatico-para-embalamento-em-blister\/blister-packing-machine-for-portioned-products-nm-25\/","title":{"rendered":"Blister packing machine for portioned products NM-25"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">A m\u00e1quina blister autom\u00e1tica de tipo plano \u00e9 amplamente utilizada para embalagens de c\u00e1psulas, comprimidos, comprimidos na ind\u00fastria farmac\u00eautica, balas de leite, gomas de mascar, compotas, chocolate l\u00edquido na ind\u00fastria alimentar, injetores, seringas, agulhas na ind\u00fastria m\u00e9dica, m\u00e1scaras faciais e oculares na ind\u00fastria cosm\u00e9tica e v\u00e1rios outros produtos em todos os tipos de formas e combina\u00e7\u00f5es de embalagem e selagem de alum\u00ednio-alum\u00ednio, alum\u00ednio-pl\u00e1stico, papel-pl\u00e1stico. O equipamento \u00e9 equipado com um dispositivo do molde do trilha-tipo que forne\u00e7a a qualidade excelente. O tamanho m\u00e1ximo do blister \u00e9 de 250x110 mm, a profundidade das c\u00e9lulas \u00e9 de 10 mm. Adequado para uso na produ\u00e7\u00e3o de alimentos e embalagem de creme de por\u00e7\u00e3o, mel, gel\u00e9ia, manteiga. A capacidade \u00e9 de 9000-12000 blisters por hora. M\u00e1xima automatiza\u00e7\u00e3o de todos os processos. Fabricado em a\u00e7o inoxid\u00e1vel de acordo com as normas GMP. Fornecemos instru\u00e7\u00f5es detalhadas para a instala\u00e7\u00e3o do equipamento blister. Manual do utilizador e ficha t\u00e9cnica em ingl\u00eas. Antes de enviar o equipamento ao cliente, ele \u00e9 verificado e testado na produ\u00e7\u00e3o. A integralidade e a operacionalidade s\u00e3o garantidas. Mantemos um stock de pe\u00e7as e consum\u00edveis em stock. O pre\u00e7o \u00e9 baseado na entrega na cidade do comprador.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>A m\u00e1quina blister autom\u00e1tica de tipo plano \u00e9 amplamente utilizada para embalagens de c\u00e1psulas, comprimidos, comprimidos na ind\u00fastria farmac\u00eautica, balas de leite, gomas de mascar, compotas, chocolate l\u00edquido na ind\u00fastria alimentar, injetores, seringas, agulhas na ind\u00fastria m\u00e9dica, m\u00e1scaras faciais e oculares na ind\u00fastria cosm\u00e9tica e v\u00e1rios outros produtos em todos os tipos de formas e&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4393,298,4440,3019],"tags":[59,43,178,175,161,41,55,63,60],"class_list":["post-856","post","type-post","status-publish","format-gallery","hentry","category-blister-de-papel-para-comprimidos","category-equipamento-automatico-para-embalamento-em-blister","category-linha-de-producao-de-embalagens-blister","category-producao-de-blister-farmacia","tag-blitzing","tag-catalogo-de-equipamentos","tag-embalagem-blister","tag-equipamento-de-embalagem","tag-equipamento-de-enchimento","tag-equipamentos-da-europa","tag-maquina-de-bolhas","tag-maquina-farmaceutica","tag-producao-de-bolhas","post_format-post-format-gallery"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":". Autor Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-equipamento\/author\/roman\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-equipamento\/equipamento-com-avaliacoes\/farmacia\/comprimidos-blister\/blister-de-papel-para-comprimidos\/\" rel=\"category tag\">BLISTER DE PAPEL PARA COMPRIMIDOS<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-equipamento\/equipamento-de-embalamento-automatico\/equipamento-automatico-para-embalamento-em-blister\/\" rel=\"category tag\">EQUIPAMENTO AUTOM\u00c1TICO PARA EMBALAMENTO EM BLISTER<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-equipamento\/equipamento-com-avaliacoes\/farmacia\/producao-de-blister\/linha-de-producao-de-embalagens-blister\/\" rel=\"category tag\">LINHA DE PRODU\u00c7\u00c3O DE EMBALAGENS BLISTER<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-equipamento\/equipamento-com-avaliacoes\/farmacia\/producao-de-blister-farmacia\/\" rel=\"category tag\">PRODU\u00c7\u00c3O DE BLISTER<\/a>","rttpg_excerpt":"A m\u00e1quina blister autom\u00e1tica de tipo plano \u00e9 amplamente utilizada para embalagens de c\u00e1psulas, comprimidos, comprimidos na ind\u00fastria farmac\u00eautica, balas de leite, gomas de mascar, compotas, chocolate l\u00edquido na ind\u00fastria alimentar, injetores, seringas, agulhas na ind\u00fastria m\u00e9dica, m\u00e1scaras faciais e oculares na ind\u00fastria cosm\u00e9tica e v\u00e1rios outros produtos em todos os tipos de formas e...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/posts\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/posts\/856\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/media?parent=856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/categories?post=856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-equipamento\/wp-json\/wp\/v2\/tags?post=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}