{"id":69291,"date":"2024-01-16T12:56:30","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=69291"},"modified":"2025-02-27T12:50:21","modified_gmt":"2025-02-27T09:50:21","slug":"apparecchiatura-di-riempimento-programmabile-ilf-060","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/vendita-del-produttore\/attrezzature-per-riempimento-e-tappatura-di-liquidi-orali-e-sostanze-viscose-con-dispenser\/apparecchiatura-di-riempimento-programmabile-ilf-060\/","title":{"rendered":"Apparecchiatura di riempimento programmabile ILF-060"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">L'apparecchiatura di riempimento programmabile include una pompa a pistoni di iniezione controllata da PLC e pu\u00f2 erogare e riempire con precisione liquidi o semi-liquidi. Il controller PLC consente maggiori possibilit\u00e0 e offre una maggiore flessibilit\u00e0 nella gestione e nel funzionamento. La macchina \u00e8 compatta, portatile e facile da configurare e utilizzare, ideale per la maggior parte dei liquidi con un'ampia gamma di viscosit\u00e0. La macchina pu\u00f2 essere utilizzata in combinazione con un nastro trasportatore e un sistema di gate per completare una linea di produzione di riempimento completamente automatica. L'apparecchiatura \u00e8 progettata in conformit\u00e0 con i requisiti GMP, la parte di contatto \u00e8 realizzata in SS316L. Facile da smontare per la pulizia. Viene utilizzato un controller PLC, il touch screen fornisce una semplice interfaccia uomo-macchina, con la quale \u00e8 facile configurare e modificare i parametri dell'apparecchiatura. La nuova funzione di riduzione del flusso consente di ridurre la velocit\u00e0 alla fine di ogni ciclo di riempimento, eliminando la formazione di bolle e aumentando la resa. Le modalit\u00e0 di funzionamento manuale e automatico possono essere facilmente modificate durante il funzionamento. L'apparecchiatura pu\u00f2 memorizzare 20 gruppi di operazioni programmate in memoria. Calibrazione automatica delle funzioni, visualizza e produce il volume di riempimento effettivo. Il terminale viene ampliato se l'utente deve utilizzare attrezzature con un trasportatore automatico. I componenti elettronici di marchi noti forniscono un funzionamento affidabile e stabile. Manuale utente e scheda tecnica in inglese. La completezza e l'operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo si basa sulla consegna alla citt\u00e0 dell'acquirente.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;apparecchiatura di riempimento programmabile include una pompa a pistoni di iniezione controllata da PLC e pu\u00f2 erogare e riempire con precisione liquidi o semi-liquidi. Il controller PLC consente maggiori possibilit\u00e0 e offre una maggiore flessibilit\u00e0 nella gestione e nel funzionamento. La macchina \u00e8 compatta, portatile e facile da configurare e utilizzare, ideale per la maggior&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[2929,4313,2977,4417,3314,3310,4304,4338],"tags":[41,39,43,207,183,205,151,203,202,63,204,208,169],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":".. Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/vendita-del-produttore\/attrezzature-per-riempimento-e-tappatura-di-liquidi-orali-e-sostanze-viscose-con-dispenser\/\" rel=\"category tag\">ATTREZZATURE PER RIEMPIMENTO E TAPPATURA DI LIQUIDI ORALI E SOSTANZE VISCOSE CON DISPENSER<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/tappatura-fiale\/chiusure-per-fiale\/\" rel=\"category tag\">CHIUSURE PER FIALE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/linea-di-riempimento\/\" rel=\"category tag\">LINEA DI RIEMPIMENTO<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/acquista-una-linea-di-riempimento\/linea-di-riempimento-del-latte-acquista-una-linea-di-riempimento\/\" rel=\"category tag\">LINEA DI RIEMPIMENTO DEL LATTE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/linea-di-riempimento\/linea-di-riempimento-del-latte\/\" rel=\"category tag\">LINEA DI RIEMPIMENTO DEL LATTE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/linea-di-riempimento\/linea-di-riempimento-pet\/\" rel=\"category tag\">LINEA DI RIEMPIMENTO PET<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/tappatura-fiale\/macchina-per-tappatura-fiale\/\" rel=\"category tag\">MACCHINA PER TAPPATURA FIALE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/pompa-a-vuoto\/pompa-farmaceutica-a-vuoto\/\" rel=\"category tag\">POMPA FARMACEUTICA A VUOTO<\/a>","rttpg_excerpt":"L'apparecchiatura di riempimento programmabile include una pompa a pistoni di iniezione controllata da PLC e pu\u00f2 erogare e riempire con precisione liquidi o semi-liquidi. Il controller PLC consente maggiori possibilit\u00e0 e offre una maggiore flessibilit\u00e0 nella gestione e nel funzionamento. La macchina \u00e8 compatta, portatile e facile da configurare e utilizzare, ideale per la maggior...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/69291"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=69291"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/69291\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=69291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=69291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=69291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}