{"id":68884,"date":"2024-01-16T15:05:10","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=68884"},"modified":"2025-02-26T19:26:28","modified_gmt":"2025-02-26T16:26:28","slug":"riempitrice-automatica-di-tubi-metallici-laminati-in-plastica-cym-8a","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/classifica-delle-10-migliori-attrezzature\/attrezzature-per-il-riempimento-e-la-sigillatura-di-tubi-metallici-laminati-in-plastica\/riempitrice-automatica-di-tubi-metallici-laminati-in-plastica-cym-8a\/","title":{"rendered":"Riempitrice automatica di tubi metallici laminati in plastica CYM-8A"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">Riempitrice automatica di tubi in tubi metallici laminati plastici con riscaldamento interno applicato a tubi plastici, laminati e metallici. Il tubo viene premuto automaticamente nel supporto del tubo. Il supporto flessibile adattato del tubo crea una forza di trazione che garantisce una tenuta costante di alta qualit\u00e0 del tubo. I sistemi di regolazione automatica della marcatura del colore mediante l'azionamento passo-passo del supporto del tubo sono adattati per tubi ovali o profilati. La trasmissione manuale del sistema di carico fornisce una capacit\u00e0 di carico stabile. L'elemento riscaldante originale svizzero LEISTER. La superficie interna del tubo \u00e8 sigillata con aria calda, mentre la superficie esterna \u00e8 raffreddata facendo circolare l'acqua di raffreddamento, che d\u00e0 un'efficace sigillatura eccellente. Ventilatore (made in Taiwan) rilascia gas tossici generati durante il riscaldamento, all'aperto. Dopo aver sigillato il tubo, il sistema di raffreddamento ad aria impedisce il riscaldamento dei prodotti simili a unguenti confezionati. Sistema di controllo automatico dello SPA. La cassa \u00e8 realizzata in acciaio inossidabile di alta qualit\u00e0. La macchina pu\u00f2 essere collegata con un emulsionante, un'astucciatrice, una riempitrice, ecc. per creare una linea di produzione. Questo modello \u00e8 facile da usare utilizzando tubi di vari diametri. Processo automatico di imballaggio, sigillatura e stampa del numero di lotto in una macchina. Esistono funzioni come l'alimentazione automatica dei tubi sul desktop della macchina, lo spurgo automatico (pulizia) dei tubi, la regolazione automatica delle marcature di colore nel supporto del tubo, il riempimento automatico dei tubi e la sigillatura. La velocit\u00e0 \u00e8 controllata da un inverter. La capacit\u00e0 produttiva \u00e8 realizzata e controllata automaticamente. Il pennello meccanico stampa automaticamente il codice nella posizione impostata. Interfaccia uomo-macchina con controllo diretto e visualizzazione. Il dispositivo di riempimento del tubo adsorbente e localizzante \u00e8 controllato dal generatore di vuoto originale FESTO. Rilevamento automatico dell'inversione della direzione del tubo: la fotocellula Omron pu\u00f2 rilevare con precisione un tubo invertito. Telecamera di indicizzazione. Manuale utente e scheda tecnica in inglese. La completezza e l'operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo si basa sulla consegna alla citt\u00e0 dell'acquirente.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Riempitrice automatica di tubi in tubi metallici laminati plastici con riscaldamento interno applicato a tubi plastici, laminati e metallici. Il tubo viene premuto automaticamente nel supporto del tubo. Il supporto flessibile adattato del tubo crea una forza di trazione che garantisce una tenuta costante di alta qualit\u00e0 del tubo. I sistemi di regolazione automatica della&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[2932,4406,4594,4593,4596,3039],"tags":[39,43,168,155,189,222,194,191,154,153],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":".. Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/classifica-delle-10-migliori-attrezzature\/attrezzature-per-il-riempimento-e-la-sigillatura-di-tubi-metallici-laminati-in-plastica\/\" rel=\"category tag\">Attrezzature per il riempimento e la sigillatura di tubi metallici laminati in plastica<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/coperchi-per-macchine-per-confezionatrici-sottovuoto\/\" rel=\"category tag\">COPERCHI PER MACCHINE PER CONFEZIONATRICI SOTTOVUOTO<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/macchina-per-tubare\/macchina-per-riempimento-tubazioni-manuale\/\" rel=\"category tag\">MACCHINA PER RIEMPIMENTO TUBAZIONI MANUALE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/macchina-per-tubare\/macchina-per-tubare-da-acquistare\/\" rel=\"category tag\">MACCHINA PER TUBARE DA ACQUISTARE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/acquista-omogeneizzatore\/omogeneizzatore-domestico-da-acquistare\/\" rel=\"category tag\">OMOGENEIZZATORE DOMESTICO DA ACQUISTARE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/tubo-di-plastica\/\" rel=\"category tag\">TUBO DI PLASTICA<\/a>","rttpg_excerpt":"Riempitrice automatica di tubi in tubi metallici laminati plastici con riscaldamento interno applicato a tubi plastici, laminati e metallici. Il tubo viene premuto automaticamente nel supporto del tubo. Il supporto flessibile adattato del tubo crea una forza di trazione che garantisce una tenuta costante di alta qualit\u00e0 del tubo. I sistemi di regolazione automatica della...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68884"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=68884"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68884\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=68884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=68884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=68884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}