{"id":68832,"date":"2024-01-16T11:07:20","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=68832"},"modified":"2025-02-26T18:59:22","modified_gmt":"2025-02-26T15:59:22","slug":"attrezzatura-automatica-per-il-confezionamento-di-liquidi-e-sostanze-viscose-szp-23","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/classifica-delle-10-migliori-attrezzature\/attrezzature-automatiche-per-la-distribuzione-e-il-confezionamento-di-prodotti-farmaceutici\/attrezzatura-automatica-per-il-confezionamento-di-liquidi-e-sostanze-viscose-szp-23\/","title":{"rendered":"Attrezzatura automatica per il confezionamento di liquidi e sostanze viscose SZP-23"},"content":{"rendered":"\r\n<p>La confezionatrice automatica per liquidi e sostanze viscose viene utilizzata per il confezionamento di prodotti come shampoo, lozione, olio, miele, marmellate e cos\u00ec via, utilizzati nell&#8217;industria alimentare e cosmetica, per il confezionamento di prodotti chimici domestici. Manuale utente e scheda tecnica in inglese. La completezza e l&#8217;operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo si basa sulla consegna alla citt\u00e0 dell&#8217;acquirente.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La confezionatrice automatica per liquidi e sostanze viscose viene utilizzata per il confezionamento di prodotti come shampoo, lozione, olio, miele, marmellate e cos\u00ec via, utilizzati nell&#8217;industria alimentare e cosmetica, per il confezionamento di prodotti chimici domestici. Manuale utente e scheda tecnica in inglese. La completezza e l&#8217;operativit\u00e0 sono garantite. Manteniamo uno stock di parti e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[2930],"tags":[41,39,175,57,58,129,130,182,99],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":".. Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/classifica-delle-10-migliori-attrezzature\/attrezzature-automatiche-per-la-distribuzione-e-il-confezionamento-di-prodotti-farmaceutici\/\" rel=\"category tag\">Attrezzature automatiche per la distribuzione e il confezionamento di prodotti farmaceutici<\/a>","rttpg_excerpt":"La confezionatrice automatica per liquidi e sostanze viscose viene utilizzata per il confezionamento di prodotti come shampoo, lozione, olio, miele, marmellate e cos\u00ec via, utilizzati nell&#8217;industria alimentare e cosmetica, per il confezionamento di prodotti chimici domestici. Manuale utente e scheda tecnica in inglese. La completezza e l&#8217;operativit\u00e0 sono garantite. Manteniamo uno stock di parti e...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68832"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=68832"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68832\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=68832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=68832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=68832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}