{"id":68685,"date":"2024-01-16T11:09:31","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=68685"},"modified":"2025-02-26T17:26:50","modified_gmt":"2025-02-26T14:26:50","slug":"macchina-riempitrice-automatica-di-capsule-hmr-8","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/macchine-per-riempire-capsule-di-gelatina-dura-con-polveri\/macchina-riempitrice-automatica-di-capsule-hmr-8\/","title":{"rendered":"Macchina riempitrice automatica di capsule HMR-8"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">Macchina di rifornimento automatica della capsula. Piccolo volume, basso consumo energetico, facile da cambiare moduli. Funzionamento e pulizia facili. Vibrazioni ridotte, livello di rumore inferiore a 75 dB quando si esegue alla massima velocit\u00e0. Le differenze di data di riempimento sono controllate entro = 3%. Tasso di riempimento della capsula &gt; 99%. Tutte le parti rotanti dell'apparecchiatura sono completamente chiuse, mantenendo cos\u00ec condizioni di lubrificazione eccellenti. La superficie di lavoro ha un trattamento speciale, evitando la contaminazione incrociata con medecine. Il dispositivo di aggancio ha una protezione che impedisce il riempimento eccessivo delle capsule e la contaminazione della superficie di lavoro. L'attrezzatura \u00e8 fornita dell'interfaccia uomo-macchina di SIEMENS (regolatore compreso dello SPA, schermo di cristallo che visualizza lo stato a macchina, dati dell'uscita, movimento vuoto della capsula, stato della polvere, nessun allarme della scarsit\u00e0 della polvere e della capsula, visualizzazione e tempo di risoluzione dei problemi). Manuale utente e scheda tecnica in inglese. La completezza e l'operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo si basa sulla consegna alla citt\u00e0 dell'acquirente.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Macchina di rifornimento automatica della capsula. Piccolo volume, basso consumo energetico, facile da cambiare moduli. Funzionamento e pulizia facili. Vibrazioni ridotte, livello di rumore inferiore a 75 dB quando si esegue alla massima velocit\u00e0. Le differenze di data di riempimento sono controllate entro = 3%. Tasso di riempimento della capsula &gt; 99%. Tutte le parti&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[4628,2897],"tags":[161,39,83,81,43,85,84,63,143],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":".. Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-farmaceutiche-seattle\/\" rel=\"category tag\">Attrezzature farmaceutiche Seattle<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/macchine-per-riempire-capsule-di-gelatina-dura-con-polveri\/\" rel=\"category tag\">MACCHINE PER RIEMPIRE CAPSULE DI GELATINA DURA CON POLVERI<\/a>","rttpg_excerpt":"Macchina di rifornimento automatica della capsula. Piccolo volume, basso consumo energetico, facile da cambiare moduli. Funzionamento e pulizia facili. Vibrazioni ridotte, livello di rumore inferiore a 75 dB quando si esegue alla massima velocit\u00e0. Le differenze di data di riempimento sono controllate entro = 3%. Tasso di riempimento della capsula &gt; 99%. Tutte le parti...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68685"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=68685"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/68685\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=68685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=68685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=68685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}