{"id":686,"date":"2024-01-16T13:37:35","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=686"},"modified":"2025-02-27T00:36:28","modified_gmt":"2025-02-26T21:36:28","slug":"rilevatore-elettronico-di-peso-ad-alta-velocita-e-precisione-dk-05","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-per-confezionamento\/attrezzature-per-il-controllo-del-peso-e-la-selezione-di-scatole-di-cartone-con-medicinali\/rilevatore-elettronico-di-peso-ad-alta-velocita-e-precisione-dk-05\/","title":{"rendered":"Rilevatore elettronico di peso ad alta velocit\u00e0 e precisione DK-05"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">Rilevatore elettronico ad alta velocit\u00e0 ad alta precisione per il controllo del peso, utilizzato per prodotti farmaceutici, cosmetici e medici confezionati in imballaggi di cartone. La velocit\u00e0 di prova \u00e8 di 50-160 pacchetti al minuto. L'errore \u00e8 di 1 grammo. Controllo del peso da 5 a 1000 grammi. Peso 120 kg. Viene utilizzata un'unit\u00e0 di peso prodotta in Germania. Forniamo una gamma completa di servizi: installazione, formazione, start-up, riparazione. Progettazione meccanica semplice.\u00a0Conforme allo standard GMP. Forniamo istruzioni dettagliate per la configurazione di questo modello di macchina di controllo del peso. Prima della spedizione, le macchine di controllo del peso vengono controllate e testate in produzione. Manuale utente e scheda tecnica in inglese. La completezza e l'operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo include la consegna alla citt\u00e0 dell'acquirente.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Rilevatore elettronico ad alta velocit\u00e0 ad alta precisione per il controllo del peso, utilizzato per prodotti farmaceutici, cosmetici e medici confezionati in imballaggi di cartone. La velocit\u00e0 di prova \u00e8 di 50-160 pacchetti al minuto. L&#8217;errore \u00e8 di 1 grammo. Controllo del peso da 5 a 1000 grammi. Peso 120 kg. Viene utilizzata un&#8217;unit\u00e0 di&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[291],"tags":[39,175,149,105,43,63,104],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":". Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/roman\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-per-confezionamento\/attrezzature-per-il-controllo-del-peso-e-la-selezione-di-scatole-di-cartone-con-medicinali\/\" rel=\"category tag\">ATTREZZATURE PER IL CONTROLLO DEL PESO E LA SELEZIONE DI SCATOLE DI CARTONE CON MEDICINALI<\/a>","rttpg_excerpt":"Rilevatore elettronico ad alta velocit\u00e0 ad alta precisione per il controllo del peso, utilizzato per prodotti farmaceutici, cosmetici e medici confezionati in imballaggi di cartone. La velocit\u00e0 di prova \u00e8 di 50-160 pacchetti al minuto. L'errore \u00e8 di 1 grammo. Controllo del peso da 5 a 1000 grammi. Peso 120 kg. Viene utilizzata un'unit\u00e0 di...","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/686"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}