{"id":2931,"date":"2024-01-16T11:46:20","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/gidravlicheskij-press-lp-300\/?lang=zh-hans"},"modified":"2025-02-27T01:47:44","modified_gmt":"2025-02-26T22:47:44","slug":"pressa-idraulica-lp-300","status":"publish","type":"post","link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-idraulica-manuale-da-pavimento\/pressa-idraulica-lp-300\/","title":{"rendered":"Pressa idraulica LP-300"},"content":{"rendered":"<pre id=\"translation\" class=\"textinput textlayer textlayer_dst translation state-fadeaway state-focused\" tabindex=\"-1\" contenteditable=\"plaintext-only\" spellcheck=\"false\" data-tracking-data=\"{&quot;id&quot;: &quot;box-dst&quot;}\">Modello di pressa idraulica automatica per la pressatura di compresse fino a 250 mm di diametro. \u00c8 possibile installare fino a 10 paia di utensili da stampa. La pressa idraulica \u00e8 realizzata in acciaio inossidabile. La capacit\u00e0 massima \u00e8 di 2000 compresse all'ora. C'\u00e8 accesso a tutte le parti della stampa da tutti i lati. L'area di lavoro \u00e8 coperta da schermi di plastica trasparente. Una stazione idraulica \u00e8 fornita nel kit. C'\u00e8 una regolazione regolare della forza di pressatura e della produttivit\u00e0. La forza di pressatura principale \u00e8 di 300 tonnellate. Adatto per la produzione di tavolette di varie forme con loghi. Forniamo istruzioni dettagliate per la configurazione della pressa e la produzione di compresse. Prima di inviare la pressa al cliente, viene controllata e testata in produzione. La completezza e l'operativit\u00e0 sono garantite. Manteniamo uno stock di parti e materiali di consumo in magazzino. Il prezzo include i pagamenti doganali in USA e la consegna alla citt\u00e0 dell'acquirente.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Modello di pressa idraulica automatica per la pressatura di compresse fino a 250 mm di diametro. \u00c8 possibile installare fino a 10 paia di utensili da stampa. La pressa idraulica \u00e8 realizzata in acciaio inossidabile. La capacit\u00e0 massima \u00e8 di 2000 compresse all&#8217;ora. C&#8217;\u00e8 accesso a tutte le parti della stampa da tutti i lati&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"two_page_speed":[]},"categories":[4426,4424,4428,4430,4432],"tags":[96],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":". Autore Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/author\/roman\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-idraulica-a-cavo-manuale\/\" rel=\"category tag\">PRESSA IDRAULICA A CAVO MANUALE<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-idraulica-manuale-da-pavimento\/\" rel=\"category tag\">PRESSA IDRAULICA MANUALE DA PAVIMENTO<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-idraulica-manuale-gost\/\" rel=\"category tag\">PRESSA IDRAULICA MANUALE GOST<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-per-compresse-manuale-idraulica\/\" rel=\"category tag\">PRESSA PER COMPRESSE MANUALE IDRAULICA<\/a> <a href=\"https:\/\/minipress.ru\/farmaceutico-attrezzature\/attrezzature-con-recensioni\/farmaceutica\/presse-idrauliche-manuali\/pressa-per-compresse-manuale-idraulica-presse-idrauliche-manuali\/\" rel=\"category tag\">PRESSA PER COMPRESSE MANUALE IDRAULICA<\/a>","rttpg_excerpt":"Modello di pressa idraulica automatica per la pressatura di compresse fino a 250 mm di diametro. \u00c8 possibile installare fino a 10 paia di utensili da stampa. La pressa idraulica \u00e8 realizzata in acciaio inossidabile. La capacit\u00e0 massima \u00e8 di 2000 compresse all'ora. C'\u00e8 accesso a tutte le parti della stampa da tutti i lati....","_links":{"self":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/2931"}],"collection":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/posts\/2931\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/categories?post=2931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/farmaceutico-attrezzature\/wp-json\/wp\/v2\/tags?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}