{"id":83491,"date":"2024-10-15T13:34:08","date_gmt":"2024-10-15T10:34:08","guid":{"rendered":"https:\/\/minipress.ru\/katalog\/?p=82639"},"modified":"2025-07-15T16:30:21","modified_gmt":"2025-07-15T13:30:21","slug":"machine-de-scellage-de-doypack-de-table-hq-05","status":"publish","type":"post","link":"https:\/\/minipress.ru\/equipement-pharmaceutique\/machines-demballage-sous-vide-pour-sacs\/machine-de-scellage-de-doypack-de-table-hq-05\/","title":{"rendered":"Machine de scellage de doypack de table HQ-05"},"content":{"rendered":"<p>Machine de table pour sceller des sacs\/emballages en poly\u00e9thyl\u00e8ne. Pour une utilisation dans des conditions de laboratoire et de production \u00e0 petite \u00e9chelle. Vitesse de scellage jusqu&rsquo;\u00e0 17 m\u00e8tres par minute. Poids 10 kg. Fabrication de haute qualit\u00e9, mat\u00e9riaux &#8211; acier inoxydable de qualit\u00e9 AISI 304. Fabriqu\u00e9 selon les normes GMP. Nous fournissons des instructions d\u00e9taill\u00e9es sur la configuration de l&rsquo;\u00e9quipement. Avant d&rsquo;\u00eatre envoy\u00e9 au client, l&rsquo;\u00e9quipement est v\u00e9rifi\u00e9 et test\u00e9 en usine. L&rsquo;int\u00e9gralit\u00e9 et la fonctionnalit\u00e9 sont garanties. Nous maintenons un stock de pi\u00e8ces et de consommables en stock. Le prix comprend la livraison dans la ville de l&rsquo;acheteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Machine de table pour sceller des sacs\/emballages en poly\u00e9thyl\u00e8ne. Pour une utilisation dans des conditions de laboratoire et de production \u00e0 petite \u00e9chelle. Vitesse de scellage jusqu&rsquo;\u00e0 17 m\u00e8tres par minute. Poids 10 kg. Fabrication de haute qualit\u00e9, mat\u00e9riaux &#8211; acier inoxydable de qualit\u00e9 AISI 304. Fabriqu\u00e9 selon les normes GMP. Nous fournissons des instructions&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4935],"tags":[4735,4890,175,39,4887,4783],"class_list":["post-83491","post","type-post","status-publish","format-gallery","hentry","category-machines-demballage-sous-vide-pour-sacs","tag-catalogue-dequipements-3","tag-emballage-sous-vide-2","tag-equipement-demballage","tag-equipement-pharmaceutique","tag-ligne-de-conditionnement","tag-machine-demballage","post_format-post-format-gallery"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":".. Auteure Roman Tsibulsky","author_link":"https:\/\/minipress.ru\/equipement-pharmaceutique\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/minipress.ru\/equipement-pharmaceutique\/machines-demballage-sous-vide-pour-sacs\/\" rel=\"category tag\">Machines d'emballage sous vide pour sacs<\/a>","rttpg_excerpt":"Machine de table pour sceller des sacs\/emballages en poly\u00e9thyl\u00e8ne. Pour une utilisation dans des conditions de laboratoire et de production \u00e0 petite \u00e9chelle. Vitesse de scellage jusqu&rsquo;\u00e0 17 m\u00e8tres par minute. Poids 10 kg. Fabrication de haute qualit\u00e9, mat\u00e9riaux &#8211; acier inoxydable de qualit\u00e9 AISI 304. Fabriqu\u00e9 selon les normes GMP. Nous fournissons des instructions...","_links":{"self":[{"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/posts\/83491"}],"collection":[{"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/comments?post=83491"}],"version-history":[{"count":0,"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/posts\/83491\/revisions"}],"wp:attachment":[{"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/media?parent=83491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/categories?post=83491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minipress.ru\/equipement-pharmaceutique\/wp-json\/wp\/v2\/tags?post=83491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}